{"id":2420,"date":"2025-09-21T20:41:22","date_gmt":"2025-09-21T18:41:22","guid":{"rendered":"https:\/\/www.textesrares.com\/pages\/?p=2420"},"modified":"2025-09-21T20:41:23","modified_gmt":"2025-09-21T18:41:23","slug":"bizos-gaston-1848-1904-trente-ans-dune-vie-devouee-sous-toutes-ses-formes-a-linstruction-publique","status":"publish","type":"post","link":"https:\/\/www.textesrares.com\/pages\/Histoire-de-l-education\/bizos-gaston-1848-1904-trente-ans-dune-vie-devouee-sous-toutes-ses-formes-a-linstruction-publique.html","title":{"rendered":"Bizos, Gaston (1848-1904), trente ans d&rsquo;une vie d\u00e9vou\u00e9e, sous toutes ses formes, \u00e0 l&rsquo;Instruction publique"},"content":{"rendered":"\n<p>Normalien, agr\u00e9g\u00e9, docteur \u00e8s-lettres, Gaston Bizos consacre toute sa carri\u00e8re \u00e0 l&rsquo;enseignement, dans le secondaire et le sup\u00e9rieur, au commentaire savant des oeuvres litt\u00e9raires, et \u00e0 l&rsquo;accomplissement des fonctions d&rsquo;autorit\u00e9, comme doyen, et plusieurs fois recteur d&rsquo;acad\u00e9mie : Grenoble, Dijon, Bordeaux, Montpellier, Bordeaux.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Gaston [Denis Victor] Bizos [1848-1904]. N\u00e9 le 22 d\u00e9cembre 1848, \u00e0 Paris [Seine] ; mort le 30 mai 1904, \u00e0 Bordeaux [Gironde].<br>\u00c9l\u00e8ve \u00e0 Paris du lyc\u00e9e Corneille [aujourd&rsquo;hui Henri-IV, depuis 1873].<\/p>\n\n\n\n<p>1868<br>ANCIEN \u00c9L\u00c8VE DE L&rsquo;\u00c9COLE NORMALE SUP\u00c9RIEURE<br>Ancien \u00e9l\u00e8ve de l&rsquo;\u00c9cole normale sup\u00e9rieure [1868].<br>Sont re\u00e7us, en 1868, au concours d&rsquo;entr\u00e9e de l&rsquo;\u00c9cole normale sup\u00e9rieure, dans l&rsquo;ordre de classement [r\u00e9sultats proclam\u00e9s le 17 ao\u00fbt 1868] : Gustave Bloch [1848-1923] ; Jacques Marie Crozals [1848-1915] ; Victor Brochard [1848-1907] ; Ferdinand Clerc [1848-1892] ; Paul Lec\u00e8ne [1849-1895] ; Maxime Collignon [1849-1917] ; Jacques G\u00e9belin [1848-1898] ; Jean Richepin [1849-1926] ; Berthold Zeller [1848-1899] ; Charles Bayet [1849-1918] ; Gaston Bizos [1848-1904] ; Fernand Lame [1850-1915] ; Fran\u00e7ois Albert Ginovez [1846-1887] ; Louis Lehanneur [1848-1905] ; \u00c9mile Fillion [NNN] ; Edmond Colsenet [1847-1925] ; Albert Pierre [1848-1917] ; Paul Souquet [1848-1923].<\/p>\n\n\n\n<p>Compte tenu de la guerre franco-prussienne [1870-1871], la scolarit\u00e9 est interrompue en 1870.<br>Gaston Bizos est engag\u00e9 volontaire, comme sergent fourrier dans la l\u00e9gion de Guingamp. Rejoint l&rsquo;arm\u00e9e de la Loire. Sous-officier, devient l&rsquo;officier d&rsquo;ordonnance du colonel de Salsy de janvier \u00e0 mars 1871.<br>Puis reprend sa scolarit\u00e9 rue d&rsquo;Ulm.<\/p>\n\n\n\n<p>1872<br>AGR\u00c9GATION DES LETTRES<br>Agr\u00e9gation des lettres [18 septembre 1872]. 5\/11.&nbsp;<br>Sont re\u00e7us \u00e0 l&rsquo;agr\u00e9gation des lettres en 1872, les onze candidats : Gustave Bloch [1848-1923], \u00e9l\u00e8ve sortant de l&rsquo;\u00c9cole normale sup\u00e9rieure [1868] ; Maxime Collignon [1849-1917], \u00e9l\u00e8ve sortant de l&rsquo;\u00c9cole normale sup\u00e9rieure [1868] ; \u00c9mile Fillion [NNN], \u00e9l\u00e8ve sortant de l&rsquo;\u00c9cole normale sup\u00e9rieure [1868] ; Louis F\u00e9lix Juste Marie Grandsaignes d&rsquo;Hauterive [1833-1904], charg\u00e9 de cours au lyc\u00e9e de Chamb\u00e9ry ; Gaston Bizos [1848-1904], \u00e9l\u00e8ve sortant de l&rsquo;\u00c9cole normale sup\u00e9rieure [1868] ; Henri Durand-Morimbaud [1848-1911], ancien \u00e9l\u00e8ve de l&rsquo;\u00c9cole normale sup\u00e9rieure [1867], charg\u00e9 de cours au lyc\u00e9e de Ch\u00e2teauroux ; Joseph Roger Charles Lavigne [NNN], charg\u00e9 de cours au lyc\u00e9e de Rodez ; Louis Lehanneur [1848-1905], \u00e9l\u00e8ve sortant de l&rsquo;\u00c9cole normale sup\u00e9rieure [1868] ; Eug\u00e8ne Berthault [1844-1896], ancien \u00e9l\u00e8ve de l&rsquo;\u00c9cole normale sup\u00e9rieure [1864], charg\u00e9 de cours au lyc\u00e9e de Tarbes ; Pierre Vaslet [NNN], ancien \u00e9l\u00e8ve de l&rsquo;\u00c9cole normale sup\u00e9rieure [1862], charg\u00e9 de cours au lyc\u00e9e d&rsquo;Angoul\u00eame ; Nicolas Am\u00e9d\u00e9e Mercier [1828-1881], d\u00e9j\u00e0 agr\u00e9g\u00e9 de grammaire [1869], charg\u00e9 de cours au lyc\u00e9e de Nantes.<\/p>\n\n\n\n<p>1872<br>CHARG\u00c9 DE RH\u00c9TORIQUE AU LYC\u00c9E D&rsquo;AVIGNON<br>Apr\u00e8s l&rsquo;agr\u00e9gation des lettres, Gaston Bizos est nomm\u00e9, le 17 octobre 1872, charg\u00e9 de cours de rh\u00e9torique au lyc\u00e9e d&rsquo;Avignon [d\u00e9partement du Vaucluse ; acad\u00e9mie d&rsquo;Aix], en remplacement de Dauphin\u00e9.<br>Gaston Bizos ne reste en poste qu&rsquo;un an, jusqu&rsquo;au 30 septembre 1873, juste avant la date de sa nomination \u00e0 Besan\u00e7on.<\/p>\n\n\n\n<p>1873<br>PROFESSEUR AU LYC\u00c9E DE BESAN\u00c7ON<br>Le 7 octobre 1873, Gaston Bizos est charg\u00e9 de cours de rh\u00e9torique au lyc\u00e9e de Besan\u00e7on [d\u00e9partement du Doubs ; acad\u00e9mie de Besan\u00e7on], puis au 12 janvier 1874, est nomm\u00e9 professeur titulaire de rh\u00e9torique, en remplacement de Gustave Bloch [1848-1923], lui aussi normalien et agr\u00e9g\u00e9, nomm\u00e9 en octobre 1872, apr\u00e8s son agr\u00e9gation des lettres.<\/p>\n\n\n\n<p>Participe aux activit\u00e9 de la Soci\u00e9t\u00e9 d&rsquo;\u00e9mulation du Doubs.<br>Dans la s\u00e9ance publique du 16 d\u00e9cembre 1875, y lit un M\u00e9moire : Pierre Corneille et Jean Mairet. Un \u00e9pisode de la querelle du Cid.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>https:\/\/www.google.fr\/books\/edition\/M\u00e9moires\/2K1BAQAAMAAJ?hl=fr&amp;gbpv=1&amp;dq=gaston+bizos&amp;pg=PA505&amp;printsec=frontcover<\/li>\n<\/ul>\n\n\n\n<p>1877<br>DOCTORAT-\u00c8S-LETTRES \u00c0 PARIS<br>Docteur \u00e8s-lettres, en 1877, avec une th\u00e8se latine : Flori historici, vel potius rhetoris, de vero nomine, aetate qua vixerit, et scriptis.<br>[Lutetiae Parisiorum : apud E. Thorin bibliopolam. via dicta Medicis, 7. In-8, 174 p., MDCCCLXXVI (1876)]. Index.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>https:\/\/catalog.hathitrust.org\/Record\/007964386<br>La th\u00e8se est d\u00e9di\u00e9e : Carissimo magistro et ornitissimo viro\/ Gaston Boissier\/ In Galliae collegio et in Schola normali\/ Latinarum Litterarum Professori\/ Uni ex Academiae Gallicae XL\/ Gratissimi et devotissimi animi pignus\/ D. D. D.<\/li>\n<\/ul>\n\n\n\n<p>La th\u00e8se en fran\u00e7ais a pour titre : \u00c9tude sur la vie et les oeuvres de Jean de Mairet. Th\u00e8se pr\u00e9sent\u00e9e \u00e0 la Facult\u00e9 des Lettres de Paris, par Gaston Bizos, Ancien \u00e9l\u00e8ve de l&rsquo;\u00c9cole normale sup\u00e9rieure.<br>[Paris : Ernest Thorin, \u00e9diteur. Libraire du Coll\u00e8ge de France et de l&rsquo;\u00c9cole normale sup\u00e9rieure, des \u00c9coles fran\u00e7aises d&rsquo;Ath\u00e8nes et de Rome. Rue de M\u00e9dicis, 7. In-8, 400 p., 1877]. Table des mati\u00e8res.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>https:\/\/gallica.bnf.fr\/ark:\/12148\/bpt6k6457147g.r=gaston%20bizos?rk=42918;4<br>La th\u00e8se est d\u00e9di\u00e9e : A\/ Monsieur Charles Lenient\/ Professeur de Po\u00e9sie fran\u00e7aise \u00e0 la Facult\u00e9 des Lettres\/ de Paris \/\/ Hommage\/ de reconnaissance et d&rsquo;affection.<\/li>\n<\/ul>\n\n\n\n<p>Gaston Bizos a eu Charles Lenient comme enseignant \u00e0 l&rsquo;\u00c9cole normale.<br>Charles Lenient [1826-1908], ancien \u00e9l\u00e8ve de l&rsquo;\u00c9cole normale sup\u00e9rieure [1847], agr\u00e9g\u00e9 des lettres [1850], docteur \u00e8s-lettres [1855], charg\u00e9 des conf\u00e9rences de Langue et litt\u00e9rature fran\u00e7aises \u00e0 l&rsquo;\u00c9cole normale sup\u00e9rieure [1865], suppl\u00e9ant de Saint-Marc-Girardin [1801-1873] \u00e0 la Facult\u00e9 des lettres de Paris [1868-1872], dans la chaire de Po\u00e9sie fran\u00e7aise, puis professeur titulaire de 1873 \u00e0 1890.<\/p>\n\n\n\n<p>AUTOUR DES TH\u00c8SES<br>La th\u00e8se latine porte sur Lucius Annaeus Florus :<br>Lucius Annaeus Florus est un historien et po\u00e8te romain, issu d&rsquo;une famille berb\u00e8re, originaire de la province d&rsquo;Afrique romaine du II \u00e8me si\u00e8cle.<br>Son Abr\u00e9g\u00e9 de l&rsquo;histoire romaine a \u00e9t\u00e9 traduit par Camille Paganel [1797-1859] en 1823 ; par Jules Pierrot [1792-1845] en 1826 ; par Charles du Rozoir [1790-1844] en 1829 ; Fran\u00e7ois Ragon [1795-1872] en 1833.<\/p>\n\n\n\n<p>La th\u00e8se en fran\u00e7ais &lt; \u00c9tude sur la vie et les oeuvres de Jean de Mairet &gt;, publi\u00e9e en 1877 est r\u00e9\u00e9dit\u00e9e : [Gene\u0300ve : Slatkine reprints, 1970].<\/p>\n\n\n\n<p>1878<br>PROFESSEUR A LA FACULT\u00c9 DES LETTRES D&rsquo;AIX<br>Gaston Bizos, \u00e0 Aix, est nomm\u00e9 charg\u00e9 de cours de Litt\u00e9rature fran\u00e7aise [1er mars 1878], puis professeur titulaire [3 juillet 1880], en remplacement d&rsquo;Hermile Reynald [1828-1883], charg\u00e9 de cours [1867-1868], titulaire [1868-1877] de la chaire de Litt\u00e9rature fran\u00e7aise, nomm\u00e9 dans la chaire d&rsquo;Histoire [1877-1883].<\/p>\n\n\n\n<p>1878<br>PUBLICATION DES LE\u00c7ONS D&rsquo;OUVERTURE<br>Gaston Bizos, selon un usage alors g\u00e9n\u00e9ralement attendu, fait para\u00eetre le texte de sa le\u00e7on d&rsquo;ouverture : Facult\u00e9 des lettres d&rsquo;Aix. Cours de litt\u00e9rature fran\u00e7aise. Le\u00e7on d&rsquo;ouverture, par M. Gaston Bizos. (21 avril 1878.) : &lt; Richelieu protecteur de l&rsquo;art dramatique et les trois unit\u00e9s &gt;.<br>[Aix : impr. de A. Makaire. In-8, 30 p., 1878].<\/p>\n\n\n\n<p>Son enseignement \u00e0 Aix, porte notamment sur Andr\u00e9 Ch\u00e9nier et sur Alphonse de Lamartine.<\/p>\n\n\n\n<p>1881<br>LE\u00c7ON D&rsquo;OUVERTURE DE LITT\u00c9RATURE FRAN\u00c7AISE \u00c0 AIX<br>De m\u00eame, Gaston Bizos publie le texte de sa le\u00e7on d&rsquo;ouverture du cours de Litt\u00e9rature fran\u00e7aise pour l&rsquo;ann\u00e9e 1880-1881.<br>[Aix : typographie Veuve Remondet-Aubin. In-8, 27 p., 1881].<\/p>\n\n\n\n<p>1890<br>LE\u00c7ON D&rsquo;OUVERTURE DE LITT\u00c9RATURE FRAN\u00c7AISE \u00c0 AIX<br>Le\u00e7on d&rsquo;ouverture du cours de Litt\u00e9rature fran\u00e7aise \u00e0 la Facult\u00e9 des Lettres d&rsquo;Aix.<br>&lt; La Come\u0301die litte\u0301raire sous la Re\u0301volution &gt; \u00c9dit\u00e9e sous forme d&rsquo;une plaquette in-8.<\/p>\n\n\n\n<p>Dans son cours public du samedi, Gaston Bizos \u00e9tudie les auteurs suivants : le po\u00e8te et auteur dramatique Fabre d\u2019\u00c9glantine [1750-1794] ; l&rsquo;auteur dramatique Jean Louis Laya [1761-1853] ; le dramaturge Charles Albert Demoustier [1760-1801] ; le dramaturge Jean Fran\u00e7ois Collin d\u2019Harleville [1755-1806] ; l&rsquo;homme de lettres Stanislas Andrieux [1759-1833], secr\u00e9taire perp\u00e9tuel de l&rsquo;Acad\u00e9mie fran\u00e7aise ; les premi\u00e8res com\u00e9dies de Louis Beno\u00eet Picard [1769-1828].<\/p>\n\n\n\n<p>1880<br>LES FR\u00c8RES DE BOILEAU-DESPREAUX<br>Les Fr\u00e8res de Boileau-Despr\u00e9aux.<br>[Aix : Impr. Veuve Remondet-Aubin. In-8, 123 p., 1880].<br>Il s&rsquo;agit du texte de six le\u00e7ons faites par Gaston Bizos \u00e0 la Facult\u00e9 des Lettres d&rsquo;Aix<\/p>\n\n\n\n<p>Biographie du c\u00e9l\u00e8bre po\u00e8te et pol\u00e9miste du 17e si\u00e8cle au travers de ses deux fr\u00e8res, Gilles, avocat et rimeur, membre de l&rsquo;Acad\u00e9mie fran\u00e7aise, et Jacques, chanoine de la Sainte-Chapelle;<\/p>\n\n\n\n<p>1881<br>LES PO\u00c8MES DE LA MER DE JOSEPH AUTRAN<br>Les Po\u00e8mes de la mer de Joseph Autran. Conf\u00e9rence faite au Cercle artistique de Marseille, le jeudi 22 d\u00e9cembre 1881, par M. Gaston Bizos, Professeur de Litt\u00e9rature fran\u00e7aise \u00e0 la Facult\u00e9 des Lettres d&rsquo;Aix.<br>[Marseille : Typ. et Lith. Barlatier-Feissat P\u00e8re et Fils. Rue Venture, 19. In-12, 24 p., 1882].<\/p>\n\n\n\n<p>Joseph Antoine Autran est un po\u00e8te et auteur dramatique fran\u00e7ais, n\u00e9 le 20 juin 1813 \u00e0 Marseille, o\u00f9 il est mort le 6 mars 1877.<br>Les Po\u00e8mes de la mer ont \u00e9t\u00e9 \u00e9dit\u00e9s en 1852 [Paris : Michel L\u00e9vy fr\u00e8res. In-8, 348 p., 1852]. R\u00e9partis en deux &lt; livres &gt; comprenant : Vingt-six po\u00e8mes pour le premier livre ; Vingt-huit po\u00e8mes pour le deuxi\u00e8me livre.<br>https:\/\/gallica.bnf.fr\/ark:\/12148\/bpt6k5469845r\/f359.item.texteImage<\/p>\n\n\n\n<p>1883<br>\u00c9LU DOYEN DE LA FACULT\u00c9 DES LETTRES D&rsquo;AIX<br>Gaston Bizos est \u00e9lu, le 7 octobre 1883, doyen de la Facult\u00e9 des Lettres d&rsquo;Aix, en succession d&rsquo;Hermile Raynald [1828-1883], doyen de 1879 \u00e0 1883, d\u00e9c\u00e9d\u00e9 le 22 juillet 1883, \u00e0 Aix.<\/p>\n\n\n\n<p>Georges Guibal [1837-1905], ancien \u00e9l\u00e8ve de l\u2019\u00c9cole normale sup\u00e9rieure [1857], agr\u00e9g\u00e9 d\u2019histoire et g\u00e9ographie [1860], docteur \u00e8s-lettres [1863], professeur d&rsquo;Histoire \u00e0 la Facult\u00e9 des Lettres d\u2019Aix [1883-1901], est assesseur du doyen.<\/p>\n\n\n\n<p>Gaston Bizos est r\u00e9\u00e9lu comme doyen, en fonction jusqu&rsquo;au 25 octobre 1890, date de sa nomination comme recteur de l&rsquo;acad\u00e9mie de Grenoble.<\/p>\n\n\n\n<p>Comme doyen Gaston Bizos, \u00e0 la s\u00e9ance solennelle de rentr\u00e9e des Facult\u00e9s le 14 novembre 1887, prononce un discours d&rsquo;usage : Pre\u0301vost-Paradol a\u0300 Aix en 1856.<br>[Aix : J. Remondet Aubin. In-8, 1887].<\/p>\n\n\n\n<p>Est remplac\u00e9 comme doyen, de 1890 \u00e0 1894, \u00e0 Aix par Georges Guibal [1837-1905], professeur d&rsquo;Histoire, ancien assesseur de Gaston Bizos.<\/p>\n\n\n\n<p>1880<br>F\u00c9NELON \u00c9DUCATEUR<br>Gaston Bizos publie en 1886 : F\u00e9nelon \u00e9ducateur, par Gaston Bizos, ancien \u00e9l\u00e8ve de l&rsquo;\u00c9cole normale sup\u00e9rieure, professeur de litt\u00e9rature fran\u00e7aise et doyen de la Facult\u00e9 des Lettres d&rsquo;Aix,<br>[Paris : H. Lec\u00e8ne et H. Oudin, rue Bonaparte. 235 p., 1880]. Collection Classiques populaires. Portrait en frontispice.<br>https:\/\/gallica.bnf.fr\/ark:\/12148\/bpt6k9600776t.r=gaston%20bizos?rk=21459;2<br>Conna\u00eet plusieurs \u00e9ditions : en 1887 [deuxi\u00e8me \u00e9dition] ; en 1889.<\/p>\n\n\n\n<p>1885<br>APPARITION DU M\u00c9LODRAME<br>Essai sur l&rsquo;apparition du me\u0301lodrame en France au XVIIIe sie\u0300cle. Gaston Bizos<br>[Paris : Plaquette in-8. 1885].<\/p>\n\n\n\n<p>1886 &amp; 1887<br>LA FABLE ET LES FABULISTES<br>La Fable et les fabulistes au XVIIe si\u00e8cle : extraits des fables de La Fontaine et de F\u00e9nelon. Pr\u00e9c\u00e9d\u00e9s de notices : sur La Fontaine, par \u00c9mile Faguet, et sur F\u00e9nelon, par Gaston Bizos.<br>[Paris : H. Lec\u00e8ne et H. Oudin, Petite biblioth\u00e8que des auteurs fran\u00e7ais. In-8, 144 p., 1886]<\/p>\n\n\n\n<p>1890<br>RECTEUR DE L&rsquo;ACAD\u00c9MIE DE GRENOBLE<br>Gaston Bizos est nomm\u00e9, le 25 octobre 1890, recteur de l&rsquo;acad\u00e9mie de Grenoble, en remplacement de Jules G\u00e9rard [1839-1898], ant\u00e9rieurement professeur titulaire de la chaire de Philosophie \u00e0 la Facult\u00e9 des Lettres de Nancy [novembre 1879-mai 1882], en poste comme recteur de l&rsquo;acad\u00e9mie de Grenoble du 11 mai 1882 \u00e0 septembre 1890.<br>Gallois est secr\u00e9taire de l&rsquo;acad\u00e9mie<br>Le ressort de l&rsquo;acad\u00e9mie de Grenoble s&rsquo;\u00e9tend sur les quatre d\u00e9partements suivants : Is\u00e8re&nbsp;[chef-lieu acad\u00e9mique : Grenoble] ; Hautes-Alpes&nbsp;[chef-lieu : Gap] ; Ard\u00e8che [chef-lieu : Privas]&nbsp;; Dr\u00f4me [chef-lieu : Valence].<\/p>\n\n\n\n<p>Sont inspecteurs de l&rsquo;acad\u00e9mie de Grenoble : Pierre Fran\u00e7ois Xavier Stouff [1830-1899], en r\u00e9sidence \u00e0 Grenoble [Is\u00e8re] ; Meyer, en r\u00e9sidence \u00e0 Gap [Hautes-Alpes] ; \u00c9douard Lloubes [1850-NNN], en r\u00e9sidence \u00e0 Privas [Ard\u00e8che] ; Joseph Forfer [1850-1906], en r\u00e9sidence \u00e0 Valence [Dr\u00f4me].<\/p>\n\n\n\n<p>Gaston Bizos reste en poste jusqu&rsquo;au 25 novembre 1893. Est remplac\u00e9 \u00e0 Grenoble par Jean Baptiste Joseph Zeller [1841-1914], ant\u00e9rieurement recteur de l\u2019acad\u00e9mie de Chamb\u00e9ry [janvier 1889-novembre 1893], nomm\u00e9 recteur de l\u2019acad\u00e9mie de Grenoble, le 25 novembre 1893 et en fonction jusqu\u2019en mars 1898.<\/p>\n\n\n\n<p>1890-1891<br>S\u00c9ANCE DE RENTR\u00c9E DES FACULT\u00c9S.<br>En tant que recteur, il appartient \u00e0 Gaston Bizos de prononcer le discours d&rsquo;usage \u00e0 la s\u00e9ance d&rsquo;entr\u00e9e des Facult\u00e9s [dans l&rsquo;ordre canonique : Droit, Sciences, Lettres, M\u00e9decine et Pharmacie] de l&rsquo;acad\u00e9mie de Grenoble.<br>Le texte en est publi\u00e9, sous forme d&rsquo;une plaquette : Universit\u00e9 de France. Acad\u00e9mie de Grenoble. Discours prononc\u00e9 par M. Gaston Bizos, recteur de l&rsquo;acad\u00e9mie, \u00e0 la s\u00e9ance de rentr\u00e9e des Facult\u00e9s et de l&rsquo;\u00c9cole de m\u00e9decine, le 18 novembre 1890.<br>[Grenoble : Imprimerie et librairie Drevet. In-8, 7 p., 1890].<\/p>\n\n\n\n<p>Universit\u00e9 de France. Acad\u00e9mie de Grenoble. S\u00e9ance annuelle de rentr\u00e9e des Facult\u00e9s et de l&rsquo;\u00c9cole pr\u00e9paratoire de m\u00e9decine et de pharmacie, le 7 novembre 1891. Discours de M. le recteur, pr\u00e9sident (Gaston Bizos).<br>[Grenoble : Imprimerie et librairie Drevet. In-8, 8 p., 1891].<\/p>\n\n\n\n<p>1893<br>RECTEUR DE L&rsquo;ACAD\u00c9MIE DE DIJON<br>Gaston Bizos est nomm\u00e9, le 7 d\u00e9cembre 1893, recteur de l\u2019acad\u00e9mie de Dijon [1893-1898], en remplacement de Charles Chappuis [1822-1897], nomm\u00e9 Inspecteur g\u00e9n\u00e9ral de l\u2019enseignement primaire [1894-1897], recteur de l\u2019acad\u00e9mie de Dijon de 1880 \u00e0 d\u00e9cembre 1893.<br>Le ressort de l\u2019acad\u00e9mie de Dijon s&rsquo;\u00e9tend sur les cinq d\u00e9partements de la C\u00f4te-d&rsquo;Or [chef-lieu&nbsp;: Dijon] ; de l&rsquo;Aube [chef-lieu&nbsp;: Troyes] ; de la Haute-Marne [chef-lieu&nbsp;: Chaumont] ; de la Ni\u00e8vre [chef-lieu&nbsp;: Nevers] ; de l&rsquo;Yonne [chef-lieu&nbsp;: Auxerre].<\/p>\n\n\n\n<p>Gaston Bizos reste en fonction, comme recteur de l\u2019acad\u00e9mie de Dijon, jusqu\u2019au 1er f\u00e9vrier 1898, date de sa nomination comme recteur de l\u2019acad\u00e9mie de Montpellier.<\/p>\n\n\n\n<p>Est remplac\u00e9 \u00e0 Dijon par Charles Adam [1857-1940], ancien recteur de l&rsquo;acad\u00e9mie de Clermont-Ferrand [1897-1898].<\/p>\n\n\n\n<p>1894<br>SOCI\u00c9T\u00c9 BOURGUIGNONNE DE G\u00c9OGRAPHIE ET D&rsquo;HISTOIRE<br>Alors que Gaston Bizos est recteur de l&rsquo;acad\u00e9mie de Dijon, est \u00e9lu membre de la Soci\u00e9t\u00e9 Bourguignonne de G\u00e9ographie et d&rsquo;Histoire.<br>Sa candidature est pr\u00e9sent\u00e9e par Gabriel d\u2019Hugues [1827-1902], professeur de Litt\u00e9rature \u00e9trang\u00e8re \u00e0 la Facult\u00e9 des Lettres de Dijon et Paul Gaffarel [1843-1920], doyen de la Facult\u00e9 des Lettres de Dijon, tous les deux anciens normaliens.<br>Gaston Bizos est \u00e9lu le 13 avril 1894.<\/p>\n\n\n\n<p>1898<br>RECTEUR DE L&rsquo;ACAD\u00c9MIE DE MONTPELLIER<br>Recteur de l\u2019acad\u00e9mie de Montpellier, pour quelques mois, du 1er f\u00e9vrier au 15 octobre 1898, en remplacement de Jules G\u00e9rard [1839-1898], d\u00e9c\u00e9d\u00e9 le 2 janvier 1898.<br>Le ressort de l\u2019acad\u00e9mie de Montpellier s\u2019\u00e9tend sur les cinq d\u00e9partements suivants&nbsp;: H\u00e9rault [chef-lieu : Montpellier]&nbsp;; Aude [chef-lieu : Carcassonne]&nbsp;; Gard [chef-lieu : N\u00eemes]&nbsp;; Loz\u00e8re [chef-lieu : Mende]&nbsp;; Pyr\u00e9n\u00e9es-Orientales [chef-lieu : Perpignan].<\/p>\n\n\n\n<p>Remplac\u00e9 comme recteur par Antoine Benoist [1846-1922], nomm\u00e9 recteur de l\u2019acad\u00e9mie de Montpellier en octobre 1898, et en fonction jusqu&rsquo;en 1919, ann\u00e9e de sa mise \u00e0 la retraite.<\/p>\n\n\n\n<p>1898<br>RECTEUR DE L&rsquo;ACAD\u00c9MIE DE BORDEAUX<br>Gaston Bizos est nomm\u00e9, le 15 octobre 1898, recteur de l&rsquo;acad\u00e9mie de Bordeaux, en remplacement d&rsquo;Auguste Couat [1846-1898], ant\u00e9rieurement recteur de l&rsquo;acad\u00e9mie de Douai, recteur de l&rsquo;acad\u00e9mie de Bordaux depuis le 6 d\u00e9cembre 1890, d\u00e9c\u00e9d\u00e9 en fonction le 21 juillet 1898.<br>Le ressort de l&rsquo;acad\u00e9mie de Bordeaux s&rsquo;\u00e9tend sur les cinq d\u00e9partements suivants : Gironde [chef-lieu : Bordeaux] ; Dordogne [chef-lieu : P\u00e9rigueux] ; Landes [chef-lieu : Mont-de-Marsan] ; Lot-et-Garonne [chef-lieu : Agen] ; Basses-Pyr\u00e9n\u00e9es [chef-lieu : Pau].<\/p>\n\n\n\n<p>Gaston Bizos d\u00e9c\u00e8de en fonction le 30 mai 1904<br>Est remplac\u00e9 comme recteur par Raymond Thamin [1857-1933], ant\u00e9rieurement recteur de l&rsquo;acad\u00e9mie de Rennes [juin 1900-mai 1904], en poste \u00e0 Bordeaux, de mai 1904 \u00e0 octobre 1922.<\/p>\n\n\n\n<p>D\u00c9CORATION<br>L\u00e9gion d&rsquo;honneur : Chevalier [19 juillet 1892] ; Officier [12 janvier 1900].<\/p>\n\n\n\n<p>AUTRES PUBLICATIONS<br>1883.<br>Richard Coeur-de-Lion poe\u0300te, par&nbsp;Gaston Bizos<br>Publi\u00e9 dans les Annales de Provence, et en tir\u00e9 \u00e0 part :<br>[Marseille : A. Zaratin. 1883].<\/p>\n\n\n\n<p>1887.<br>Un essai de drame historique en prose au XVIIIe si\u00e8cle. Le Fran\u00e7ois II du pr\u00e9sident H\u00e9nault.<br>Publi\u00e9 dans la Revue d&rsquo;art dramatique, 1er juin 1887, puis en tir\u00e9 \u00e0 part [Pagin\u00e9 251-264 In-8. 1887].<\/p>\n\n\n\n<p>1889.<br>Andr\u00e9 Ch\u00e9nier auteur dramatique.<br>Publi\u00e9 dans la Revue d&rsquo;art dramatique, avril-juin 1889, puis en tir\u00e9 \u00e0 part [(S. l.) In-16, pagin\u00e9 257-265. 1889].<br>S&rsquo;inscrit dans un mouvement de regain d&rsquo;int\u00e9r\u00eat de l&rsquo;\u00e9poque pour Andr\u00e9 Ch\u00e9nier.<\/p>\n\n\n\n<p>1891.<br>Ronsard, par G. Bizos. Ancien \u00e9l\u00e8ve de l&rsquo;\u00c9cole normale sup\u00e9rieure. Ancien professeur de Litt\u00e9rature fran\u00e7aise \u00e0 la Facult\u00e9 des Lettres d&rsquo;Aix. Recteur de l&rsquo;acad\u00e9mie de Dijon.<br>[Paris : Soci\u00e9t\u00e9 fran\u00e7aise d&rsquo;Imprimerie et de Librairie (ancienne Maison Lec\u00e8ne, Oudin et C*] 15, rue de Cluny. In-8, 238 p., 1891]. Collection des classiques populaires. Table des mati\u00e8res. Table des gravures.<br>Ce volume contient de nombreuses reproductions de la Biblioth\u00e8que nationale et du mus\u00e9e de Versailles.<br>Fait partie de la quarantaine de volumes de la collection, dirig\u00e9e par \u00c9mile Faguet [1847-1916].<br>R\u00e9\u00e9dit\u00e9 en 1897.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>https:\/\/gallica.bnf.fr\/ark:\/12148\/bpt6k97443657\/f8.item.texteImage<\/li>\n<\/ul>\n\n\n\n<p>1891.<br>Philippe Quinault.<br>Revue d&rsquo;art dramatique. Tome XXII (avril-juin 1891).<br>Publi\u00e9 en tir\u00e9 \u00e0 part in-8. Pagin\u00e9 129-154.&nbsp;<\/p>\n\n\n\n<p>1895.<br>Galerie fran\u00e7aise. Haute-Marne, par Ferdinand Galle [\u2026]. Pr\u00e9face par M. Gaston Bizos.<br>[Paris : Curel, Gougis et Cie. In-18, 1895].<\/p>\n\n\n\n<p>1903.<br>Congr\u00e8s des Soci\u00e9t\u00e9s savantes \u00e0 Bordeaux. Discours prononc\u00e9s \u00e0 la s\u00e9ance g\u00e9n\u00e9rale du congr\u00e8s, le 18 avril 1903, par M. Henry Omont,\u2026 M. Camille Jullian,\u2026 M. Gaston Bizos].<br>[Paris : Impr. nationale. In-12, 26 p., 1903].<\/p>\n\n\n\n<p>C\u00c9L\u00c9BRATION<br>Charles Bayet [1849-1918], directeur de l&rsquo;Enseignement sup\u00e9rieur, prononce un discours aux obs\u00e8ques civiles de M. Bizos.<br>Publi\u00e9 dans la Revue internationale de l&rsquo;Enseignement. Volume 47. 1904. Page 537.<br>https:\/\/education.persee.fr\/doc\/revin_1775-6014_1904_num_47_1_9260<\/p>\n\n\n\n<p>SOURCE<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fran\u00e7oise Huguet et Boris Nogu\u00e8s. Les Professeurs des facult\u00e9s des lettres et des sciences en France au XIXe si\u00e8cle (1808-1880).<br>http:\/\/facultes19.ish-lyon.cnrs.fr\/fiche.php?indice=104<\/li>\n\n\n\n<li>Jean-Fran\u00e7ois Condette. Les Recteurs d\u2019Acad\u00e9mie en France de 1808 \u00e0 1940. Tome II, Dictionnaire biographique. [Paris\u00a0: Institut national de recherche p\u00e9dagogique.<br>Collection\u00a0: Histoire biographique de l\u2019enseignement. In-8, 411 p., 2006].<br>https:\/\/www.persee.fr\/doc\/inrp_0298-5632_2006_ant_12_2_4242<\/li>\n\n\n\n<li>Guillaume Flamerie\u00a0de\u00a0Lachapelle : Florus, mod\u00e8le et contre-mod\u00e8le en France, du \u201cM\u00e9moire sur les abr\u00e9g\u00e9s chronologiques\u201d, du pr\u00e9sident H\u00e9nault \u00e0 la th\u00e8se de G.\u00a0Bizos (1761-1876).<br>https:\/\/books.openedition.org\/ausonius\/19041?lang=fr<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Normalien, agr\u00e9g\u00e9, docteur \u00e8s-lettres, Gaston Bizos (1848-1904) consacre toute sa carri\u00e8re \u00e0 l&rsquo;enseignement, dans le secondaire et le sup\u00e9rieur, au commentaire savant des oeuvres litt\u00e9raires, et \u00e0 l&rsquo;accomplissement des fonctions d&rsquo;autorit\u00e9, comme doyen, et plusieurs fois recteur d&rsquo;acad\u00e9mie : Grenoble, Dijon, Bordeaux, Montpellier, Bordeaux.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-2420","post","type-post","status-publish","format-standard","hentry","category-Histoire-de-l-education"],"_links":{"self":[{"href":"https:\/\/www.textesrares.com\/pages\/wp-json\/wp\/v2\/posts\/2420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.textesrares.com\/pages\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.textesrares.com\/pages\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.textesrares.com\/pages\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.textesrares.com\/pages\/wp-json\/wp\/v2\/comments?post=2420"}],"version-history":[{"count":1,"href":"https:\/\/www.textesrares.com\/pages\/wp-json\/wp\/v2\/posts\/2420\/revisions"}],"predecessor-version":[{"id":2421,"href":"https:\/\/www.textesrares.com\/pages\/wp-json\/wp\/v2\/posts\/2420\/revisions\/2421"}],"wp:attachment":[{"href":"https:\/\/www.textesrares.com\/pages\/wp-json\/wp\/v2\/media?parent=2420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.textesrares.com\/pages\/wp-json\/wp\/v2\/categories?post=2420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.textesrares.com\/pages\/wp-json\/wp\/v2\/tags?post=2420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}